{"id":4413,"date":"2024-08-23T10:00:00","date_gmt":"2024-08-23T08:00:00","guid":{"rendered":"https:\/\/dombert.de\/?p=4413"},"modified":"2025-03-23T20:40:32","modified_gmt":"2025-03-23T19:40:32","slug":"teachers-successfully-defend-themselves-against-secondment","status":"publish","type":"post","link":"https:\/\/dombert.de\/en\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/","title":{"rendered":"Teachers successfully defend themselves against secondment"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"4413\" class=\"elementor elementor-4413\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e4276a e-con-full e-flex e-con e-parent\" data-id=\"6e4276a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3409881 e-con-full e-flex e-con e-child\" data-id=\"3409881\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc71df0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"dc71df0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96c8c0f elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"96c8c0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teachers successfully defend themselves against secondment<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b99b6fe e-con-full e-flex e-con e-child\" data-id=\"b99b6fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ecf84c elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4ecf84c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd27ee1 elementor-widget__width-auto elementor-widget-tablet__width-initial elementor-widget-tablet_extra__width-initial elementor-widget elementor-widget-heading\" data-id=\"fd27ee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Charlotte Blech, LL.M. (UCLA)<\/span> | <span>Dr. Beate Schulte zu Sodingen<\/span> | <span>Dr. Stephan Berndt<\/span> | <span>Franziska Wilke<\/span> | <span>Kristina D\u00f6rnenburg<\/span> | <span>Kristina Gottschalk, LL.M.oec.<\/span> | <span>Prof. Dr. Klaus Herrmann<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26dc0b2 e-con-full e-flex e-con e-child\" data-id=\"26dc0b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cdd3da elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"0cdd3da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"https:\/\/www.linkedin.com\/company\/dombert-rechtsanwaelte\/posts\/?feedView=all\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-817e979 e-con-full e-flex e-con e-parent\" data-id=\"817e979\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-465d20c8 e-con-full e-flex e-con e-child\" data-id=\"465d20c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-256c3e7f e-con-full e-flex e-con e-child\" data-id=\"256c3e7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2080595d elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2080595d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f703d0a elementor-widget__width-auto elementor-widget-tablet__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-heading\" data-id=\"7f703d0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span>Posts<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-271a1f25 elementor-widget__width-auto elementor-widget-tablet__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-heading\" data-id=\"271a1f25\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">|<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-358cbb7 elementor-widget__width-auto elementor-widget-tablet__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-heading\" data-id=\"358cbb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">23.08.2024<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7eae9527 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7eae9527\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Administrative Court of M\u00fcnster has granted the urgent applications of teachers from M\u00fcnster and the surrounding area who are fighting against their secondment to primary schools in the Ruhr region. The district government of M\u00fcnster had justified the secondment on the grounds that there was a shortage of primary school teachers, particularly in the school districts of the cities of Gelsenkirchen, Bottrop and Recklinghausen. As can be seen from the decisions of the administrative court, the secondment order was not free of discretionary errors (Ref.: 5 L 554\/24 and 5 L 619\/24 of 6 August 2024). The primary schools could have named all primary school teachers at their school who were eligible for a secondment without jeopardising the teaching provision at their own school. A lottery procedure - as was practised in some cases - was not an appropriate procedure, especially as it was not documented which teachers were even included in the lottery procedure.<\/p><p>\u00a0<\/p><p>However, the administrative court clarified that, in principle, secondments of teaching staff are permissible in order to ensure an even supply of teaching staff in an administrative district. When making a discretionary decision, public interests such as ensuring the provision of lessons and the personal disadvantages for the seconded teachers must be weighed against each other.<\/p><p>\u00a0<\/p><p>Your contacts for questions relating to childcare and school law in our practice are the lawyers\u00a0<a href=\"https:\/\/dombert.de\/en\/person\/dr-beate-schulte-zu-sodingen\/\">Dr. Beate Schulte zu Sodingen<\/a>,<a href=\"https:\/\/dombert.de\/en\/person\/franziska-wilke\/\">\u00a0Franziska Wilke<\/a>\u00a0and\u00a0<a href=\"https:\/\/dombert.de\/en\/person\/charlotte-blech-ll-m-ucla\/\">Charlotte Blech<\/a>. Contact persons for public service law are the lawyers <a href=\"https:\/\/dombert.de\/en\/person\/prof-dr-klaus-herrmann\/\">Prof. Dr. Klaus Herrmann<\/a>,\u00a0<a href=\"https:\/\/dombert.de\/en\/person\/dr-stephan-berndt\/\">Dr. Stephan Berndt<\/a>\u00a0and lawyers\u00a0<a href=\"https:\/\/dombert.de\/en\/person\/kristina-doernenburg\/\">Kristina D\u00f6rnenburg<\/a>\u00a0and\u00a0<a href=\"https:\/\/dombert.de\/en\/person\/kristina-gottschalk-ll-m-oec\/\">Kristina Gottschalk, LL.M.oec<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44a2640c e-con-full e-flex e-con e-parent\" data-id=\"44a2640c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7b25c60d e-con-full e-flex e-con e-child\" data-id=\"7b25c60d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fbbaa51 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4fbbaa51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><b>DOMBERT<\/b> Rechtsanw\u00e4lte <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68ab46dd e-con-full e-flex e-con e-child\" data-id=\"68ab46dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4ec4343 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4ec4343\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e71a4a5 elementor-widget__width-auto elementor-widget-tablet_extra__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile_extra__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"3e71a4a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Our work covers all legal issues and conflicts in which the state, municipalities or authorities are involved.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18d51a71 e-con-full e-flex e-con e-child\" data-id=\"18d51a71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4445090a elementor-widget elementor-widget-button\" data-id=\"4445090a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/dombert.de\/en\/law-firm\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">More about our firm<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79b71189 elementor-widget elementor-widget-button\" data-id=\"79b71189\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/dombert.de\/en\/#kompetenzen\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">More about our expertise<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>| Das Verwaltungsgericht M\u00fcnster hat den Eilantr\u00e4gen von Lehrkr\u00e4ften aus M\u00fcnster und Umgebung stattgegeben, die sich gegen ihre Abordnung an Grundschulen im Ruhrgebiet wehren. Die Bezirksregierung M\u00fcnster hatte die Abordnung damit begr\u00fcndet, dass insbesondere in den Schulamtsbezirken der St\u00e4dte Gelsenkirchen, Bottrop und Recklinghausen Grundschullehrkr\u00e4fte fehlten. Wie aus den Beschl\u00fcssen des Verwaltungsgerichts hervorgeht, sei die Abordnungsverf\u00fcgung [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":2114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[45],"tags":[],"secondary-autor":[115,102,92,88,89,91,90],"class_list":["post-4413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meldung","secondary-autor-charlotte-blech-ll-m-ucla","secondary-autor-dr-beate-schulte-zu-sodingen","secondary-autor-dr-stephan-berndt","secondary-autor-franziska-wilke","secondary-autor-kristina-doernenburg","secondary-autor-kristina-gottschalk-ll-m-oec","secondary-autor-prof-dr-klaus-herrmann"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung - DOMBERT Rechtsanw\u00e4lte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dombert.de\/en\/teachers-successfully-defend-themselves-against-secondment\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung - DOMBERT Rechtsanw\u00e4lte\" \/>\n<meta property=\"og:description\" content=\"| Das Verwaltungsgericht M\u00fcnster hat den Eilantr\u00e4gen von Lehrkr\u00e4ften aus M\u00fcnster und Umgebung stattgegeben, die sich gegen ihre Abordnung an Grundschulen im Ruhrgebiet wehren. Die Bezirksregierung M\u00fcnster hatte die Abordnung damit begr\u00fcndet, dass insbesondere in den Schulamtsbezirken der St\u00e4dte Gelsenkirchen, Bottrop und Recklinghausen Grundschullehrkr\u00e4fte fehlten. Wie aus den Beschl\u00fcssen des Verwaltungsgerichts hervorgeht, sei die Abordnungsverf\u00fcgung [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dombert.de\/en\/teachers-successfully-defend-themselves-against-secondment\/\" \/>\n<meta property=\"og:site_name\" content=\"DOMBERT Rechtsanw\u00e4lte\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-23T08:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-23T19:40:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dombert.de\/wp-content\/uploads\/2025\/01\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"265\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/dombert.de\\\/#\\\/schema\\\/person\\\/cab100e6259958a255ba5963a0511ae1\"},\"headline\":\"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung\",\"datePublished\":\"2024-08-23T08:00:00+00:00\",\"dateModified\":\"2025-03-23T19:40:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/\"},\"wordCount\":270,\"publisher\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dombert.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg\",\"articleSection\":[\"Meldung\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/\",\"url\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/\",\"name\":\"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung - DOMBERT Rechtsanw\u00e4lte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dombert.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg\",\"datePublished\":\"2024-08-23T08:00:00+00:00\",\"dateModified\":\"2025-03-23T19:40:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dombert.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg\",\"contentUrl\":\"https:\\\/\\\/dombert.de\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg\",\"width\":380,\"height\":265},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dombert.de\\\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/dombert.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dombert.de\\\/#website\",\"url\":\"https:\\\/\\\/dombert.de\\\/\",\"name\":\"DOMBERT Rechtsanw\u00e4lte\",\"description\":\"Wir sind Ihr kompetenter Ansprechpartner f\u00fcr alle Fragen des \u00f6ffentlichen Rechts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dombert.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dombert.de\\\/#organization\",\"name\":\"DOMBERT Rechtsanw\u00e4lte\",\"url\":\"https:\\\/\\\/dombert.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/dombert.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dombert.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Dombert-Logo_negativ_rgb.png\",\"contentUrl\":\"https:\\\/\\\/dombert.de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Dombert-Logo_negativ_rgb.png\",\"width\":459,\"height\":206,\"caption\":\"DOMBERT Rechtsanw\u00e4lte\"},\"image\":{\"@id\":\"https:\\\/\\\/dombert.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dombert-rechtsanwaelte\\\/posts\\\/?feedView=all\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dombert.de\\\/#\\\/schema\\\/person\\\/cab100e6259958a255ba5963a0511ae1\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39e40254bfea26d3a2709e0f441e4bc39c1685d2b9c174550fafa42a6f4483e7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39e40254bfea26d3a2709e0f441e4bc39c1685d2b9c174550fafa42a6f4483e7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/39e40254bfea26d3a2709e0f441e4bc39c1685d2b9c174550fafa42a6f4483e7?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"sameAs\":[\"https:\\\/\\\/dombert.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Teachers successfully defend themselves against secondment - DOMBERT Rechtsanw\u00e4lte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dombert.de\/en\/teachers-successfully-defend-themselves-against-secondment\/","og_locale":"en_GB","og_type":"article","og_title":"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung - DOMBERT Rechtsanw\u00e4lte","og_description":"| Das Verwaltungsgericht M\u00fcnster hat den Eilantr\u00e4gen von Lehrkr\u00e4ften aus M\u00fcnster und Umgebung stattgegeben, die sich gegen ihre Abordnung an Grundschulen im Ruhrgebiet wehren. Die Bezirksregierung M\u00fcnster hatte die Abordnung damit begr\u00fcndet, dass insbesondere in den Schulamtsbezirken der St\u00e4dte Gelsenkirchen, Bottrop und Recklinghausen Grundschullehrkr\u00e4fte fehlten. Wie aus den Beschl\u00fcssen des Verwaltungsgerichts hervorgeht, sei die Abordnungsverf\u00fcgung [&hellip;]","og_url":"https:\/\/dombert.de\/en\/teachers-successfully-defend-themselves-against-secondment\/","og_site_name":"DOMBERT Rechtsanw\u00e4lte","article_published_time":"2024-08-23T08:00:00+00:00","article_modified_time":"2025-03-23T19:40:32+00:00","og_image":[{"width":380,"height":265,"url":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/01\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Admin","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#article","isPartOf":{"@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/"},"author":{"name":"Admin","@id":"https:\/\/dombert.de\/#\/schema\/person\/cab100e6259958a255ba5963a0511ae1"},"headline":"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung","datePublished":"2024-08-23T08:00:00+00:00","dateModified":"2025-03-23T19:40:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/"},"wordCount":270,"publisher":{"@id":"https:\/\/dombert.de\/#organization"},"image":{"@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#primaryimage"},"thumbnailUrl":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/01\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg","articleSection":["Meldung"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/","url":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/","name":"Teachers successfully defend themselves against secondment - DOMBERT Rechtsanw\u00e4lte","isPartOf":{"@id":"https:\/\/dombert.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#primaryimage"},"image":{"@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#primaryimage"},"thumbnailUrl":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/01\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg","datePublished":"2024-08-23T08:00:00+00:00","dateModified":"2025-03-23T19:40:32+00:00","breadcrumb":{"@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#primaryimage","url":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/01\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg","contentUrl":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/01\/oeffentliches-recht-neuigkeit-dombert-rechtsanwaelte.jpg","width":380,"height":265},{"@type":"BreadcrumbList","@id":"https:\/\/dombert.de\/lehrkraefte-wehren-sich-erfolgreich-gegen-abordnung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/dombert.de\/"},{"@type":"ListItem","position":2,"name":"Lehrkr\u00e4fte wehren sich erfolgreich gegen Abordnung"}]},{"@type":"WebSite","@id":"https:\/\/dombert.de\/#website","url":"https:\/\/dombert.de\/","name":"DOMBERT Rechtsanw\u00e4lte","description":"We are your expert partner for all matters relating to public law.","publisher":{"@id":"https:\/\/dombert.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dombert.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/dombert.de\/#organization","name":"DOMBERT Rechtsanw\u00e4lte","url":"https:\/\/dombert.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/dombert.de\/#\/schema\/logo\/image\/","url":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/02\/Dombert-Logo_negativ_rgb.png","contentUrl":"https:\/\/dombert.de\/wp-content\/uploads\/2025\/02\/Dombert-Logo_negativ_rgb.png","width":459,"height":206,"caption":"DOMBERT Rechtsanw\u00e4lte"},"image":{"@id":"https:\/\/dombert.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/dombert-rechtsanwaelte\/posts\/?feedView=all"]},{"@type":"Person","@id":"https:\/\/dombert.de\/#\/schema\/person\/cab100e6259958a255ba5963a0511ae1","name":"Admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/39e40254bfea26d3a2709e0f441e4bc39c1685d2b9c174550fafa42a6f4483e7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/39e40254bfea26d3a2709e0f441e4bc39c1685d2b9c174550fafa42a6f4483e7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/39e40254bfea26d3a2709e0f441e4bc39c1685d2b9c174550fafa42a6f4483e7?s=96&d=mm&r=g","caption":"Admin"},"sameAs":["https:\/\/dombert.de"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/posts\/4413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/comments?post=4413"}],"version-history":[{"count":7,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/posts\/4413\/revisions"}],"predecessor-version":[{"id":7652,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/posts\/4413\/revisions\/7652"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/media\/2114"}],"wp:attachment":[{"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/media?parent=4413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/categories?post=4413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/tags?post=4413"},{"taxonomy":"secondary-autor","embeddable":true,"href":"https:\/\/dombert.de\/en\/wp-json\/wp\/v2\/secondary-autor?post=4413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}